{"id":68,"date":"2019-05-29T18:14:52","date_gmt":"2019-05-29T18:14:52","guid":{"rendered":"https:\/\/sunneez.com\/rinnier\/?page_id=68"},"modified":"2021-07-30T14:05:34","modified_gmt":"2021-07-30T14:05:34","slug":"latest-news","status":"publish","type":"page","link":"https:\/\/sunneez.com\/rinnier\/latest-news\/","title":{"rendered":"Latest News"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":2,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v22.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Latest News - Rinnier Development Company<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/sunneez.com\/rinnier\/latest-news\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Latest News - Rinnier Development Company\" \/>\n<meta property=\"og:url\" content=\"https:\/\/sunneez.com\/rinnier\/latest-news\/\" \/>\n<meta property=\"og:site_name\" content=\"Rinnier Development Company\" \/>\n<meta property=\"article:modified_time\" content=\"2021-07-30T14:05:34+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/sunneez.com\/rinnier\/latest-news\/\",\"url\":\"https:\/\/sunneez.com\/rinnier\/latest-news\/\",\"name\":\"Latest News - Rinnier Development Company\",\"isPartOf\":{\"@id\":\"https:\/\/sunneez.com\/rinnier\/#website\"},\"datePublished\":\"2019-05-29T18:14:52+00:00\",\"dateModified\":\"2021-07-30T14:05:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/sunneez.com\/rinnier\/latest-news\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/sunneez.com\/rinnier\/latest-news\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/sunneez.com\/rinnier\/latest-news\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/sunneez.com\/rinnier\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Latest News\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/sunneez.com\/rinnier\/#website\",\"url\":\"https:\/\/sunneez.com\/rinnier\/\",\"name\":\"Rinnier Development Company\",\"description\":\"Maryland Commercial Real Estate Brokerage\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/sunneez.com\/rinnier\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Latest News - Rinnier Development Company","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/sunneez.com\/rinnier\/latest-news\/","og_locale":"en_US","og_type":"article","og_title":"Latest News - Rinnier Development Company","og_url":"https:\/\/sunneez.com\/rinnier\/latest-news\/","og_site_name":"Rinnier Development Company","article_modified_time":"2021-07-30T14:05:34+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/sunneez.com\/rinnier\/latest-news\/","url":"https:\/\/sunneez.com\/rinnier\/latest-news\/","name":"Latest News - Rinnier Development Company","isPartOf":{"@id":"https:\/\/sunneez.com\/rinnier\/#website"},"datePublished":"2019-05-29T18:14:52+00:00","dateModified":"2021-07-30T14:05:34+00:00","breadcrumb":{"@id":"https:\/\/sunneez.com\/rinnier\/latest-news\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/sunneez.com\/rinnier\/latest-news\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/sunneez.com\/rinnier\/latest-news\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/sunneez.com\/rinnier\/"},{"@type":"ListItem","position":2,"name":"Latest News"}]},{"@type":"WebSite","@id":"https:\/\/sunneez.com\/rinnier\/#website","url":"https:\/\/sunneez.com\/rinnier\/","name":"Rinnier Development Company","description":"Maryland Commercial Real Estate Brokerage","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/sunneez.com\/rinnier\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/pages\/68"}],"collection":[{"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/comments?post=68"}],"version-history":[{"count":1,"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/pages\/68\/revisions"}],"predecessor-version":[{"id":69,"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/pages\/68\/revisions\/69"}],"wp:attachment":[{"href":"https:\/\/sunneez.com\/rinnier\/wp-json\/wp\/v2\/media?parent=68"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}